{"id":715,"date":"2010-07-09T19:41:01","date_gmt":"2010-07-09T12:41:01","guid":{"rendered":"http:\/\/www.icez.net\/blog\/?p=715"},"modified":"2010-07-09T19:42:15","modified_gmt":"2010-07-09T12:42:15","slug":"top-linux-administrative-tools","status":"publish","type":"post","link":"https:\/\/www.icez.net\/blog\/715\/top-linux-administrative-tools","title":{"rendered":"0103 | top &#8211; Linux Administrative Tools"},"content":{"rendered":"<p>\u0e40\u0e2d\u0e32\u0e21\u0e32\u0e25\u0e07 blog \u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e0b\u0e31\u0e01\u0e17\u0e35&#8230;<\/p>\n<h1>&#8221; top &#8220;<\/h1>\n<p><a href=\"http:\/\/upic.me\/e5w8j\" target=\"_blank\"><img decoding=\"async\" border=\"0\" src=\"http:\/\/upic.me\/i\/mc\/ke4ac.png\" alt=\"\" \/><\/a><br \/>\n(capture  \u0e0a\u0e49\u0e32\u0e44\u0e1b\u0e2a\u0e2d\u0e07\u0e27\u0e34 \u0e40\u0e2a\u0e35\u0e22\u0e14\u0e32\u0e22\u0e08\u0e31\u0e07)<\/p>\n<p>\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e25\u0e07\u0e40\u0e1e\u0e34\u0e48\u0e21 \u0e15\u0e34\u0e14\u0e21\u0e32\u0e01\u0e31\u0e1a os  \u0e2d\u0e22\u0e39\u0e48\u0e41\u0e25\u0e49\u0e27\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e25\u0e07\u0e41\u0e1a\u0e1a minimal \u0e02\u0e19\u0e32\u0e14\u0e44\u0e2b\u0e19<br \/>\n\u0e2b\u0e23\u0e37\u0e2d\u0e16\u0e49\u0e32\u0e17\u0e33\u0e2b\u0e32\u0e22\u0e44\u0e1b \u0e21\u0e31\u0e19\u0e08\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19  package &#8220;procps&#8221; \u0e04\u0e23\u0e31\u0e1a<\/p>\n<p><strong>\u0e21\u0e31\u0e19\u0e1a\u0e2d\u0e01\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07<\/strong><br \/>\n\u0e44\u0e25\u0e48\u0e17\u0e35\u0e25\u0e30\u0e1a\u0e23\u0e23\u0e17\u0e31\u0e14 \u0e40\u0e25\u0e22\u0e19\u0e30\u0e04\u0e23\u0e31\u0e1a (\u0e04\u0e34\u0e14\u0e08\u0e32\u0e01\u0e04\u0e48\u0e32\u0e1b\u0e01\u0e15\u0e34\u0e02\u0e2d\u0e07 centos \u0e0b\u0e36\u0e48\u0e07 os \u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e01\u0e47\u0e04\u0e25\u0e49\u0e32\u0e22\u0e46 \u0e01\u0e31\u0e19  \u0e2d\u0e32\u0e08\u0e21\u0e35\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1a\u0e49\u0e32\u0e07\u0e41\u0e25\u0e49\u0e27\u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32)<\/p>\n<p>\u0e1a\u0e23\u0e23\u0e17\u0e31\u0e14\u0e1a\u0e19\u0e2a\u0e38\u0e14<br \/>\ntop &#8211; <span style=\"color: red;\">09:13:20<\/span> <span style=\"color: green;\">up 187 days,&nbsp; 8:40<\/span>,&nbsp; <span style=\"color: purple;\">1 user<\/span>,&nbsp; <span style=\"color: blue;\">load average: 0.43, 0.66, 0.61<\/span><br \/>\n<span style=\"color: red;\">\u0e2a\u0e35\u0e41\u0e14\u0e07<\/span>: \u0e40\u0e27\u0e25\u0e32\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e02\u0e2d\u0e07 server<br \/>\n<span style=\"color: green;\">\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27<\/span>: uptime (\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 boot OS \u0e02\u0e36\u0e49\u0e19\u0e21\u0e32)<br \/>\n<span style=\"color: purple;\">\u0e2a\u0e35\u0e21\u0e48\u0e27\u0e07<\/span>: \u0e08\u0e33\u0e19\u0e27\u0e19 user \u0e17\u0e35\u0e48 login \u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e43\u0e19 shell (\u0e01\u0e32\u0e23 login \u0e2b\u0e19\u0e49\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 + ssh \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e34\u0e14 terminal \u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19)<br \/>\n<span style=\"color: blue;\">\u0e2a\u0e35\u0e19\u0e49\u0e33\u0e40\u0e07\u0e34\u0e19<\/span>: load average : \u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48 &#8220;\u0e04\u0e49\u0e32\u0e07&#8221; \u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a<span class=\"bbc_u\">\u0e40\u0e09\u0e25\u0e35\u0e48\u0e22<\/span> \u0e43\u0e19\u0e23\u0e2d\u0e1a 1 , 5 \u0e41\u0e25\u0e30 15 \u0e19\u0e32\u0e17\u0e35\u0e15\u0e32\u0e21\u0e25\u0e33\u0e14\u0e31\u0e1a<\/p>\n<p>\u0e1a\u0e23\u0e23\u0e17\u0e31\u0e14\u0e17\u0e35\u0e48 2: \u0e1a\u0e23\u0e23\u0e17\u0e31\u0e14\u0e19\u0e35\u0e49\u0e08\u0e30\u0e1a\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a process \u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e1a<br \/>\nTasks: <span style=\"color: red;\">183 total<\/span>,\u00a0 \u00a0<span style=\"color: green;\">3 running<\/span>, <span style=\"color: purple;\">180 sleeping<\/span>,\u00a0 \u00a0<span style=\"color: blue;\">0 stopped<\/span>,\u00a0 \u00a0<span style=\"color: pink;\">0 zombie<\/span><br \/>\n<span style=\"color: red;\">\u0e2a\u0e35\u0e41\u0e14\u0e07<\/span>: \u0e08\u0e33\u0e19\u0e27\u0e19 process \u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14<br \/>\n<span style=\"color: green;\">\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27<\/span>: \u0e08\u0e33\u0e19\u0e27\u0e19 process \u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e23\u0e35\u0e22\u0e01\u0e43\u0e0a\u0e49 CPU \u0e2d\u0e22\u0e39\u0e48 &#8220;\u0e13 \u0e40\u0e27\u0e25\u0e32\u0e19\u0e31\u0e49\u0e19\u0e46&#8221;<br \/>\n<span style=\"color: purple;\">\u0e2a\u0e35\u0e21\u0e48\u0e27\u0e07<\/span>: \u0e08\u0e33\u0e19\u0e27\u0e19 process \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\/\u0e44\u0e21\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e01\u0e43\u0e0a\u0e49 CPU \u0e2d\u0e22\u0e39\u0e48<br \/>\n<span style=\"color: blue;\">\u0e2a\u0e35\u0e19\u0e49\u0e33\u0e40\u0e07\u0e34\u0e19<\/span>: process \u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e30 &#8220;\u0e2b\u0e22\u0e38\u0e14&#8221; (\u0e44\u0e2d\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e41\u0e19\u0e48\u0e43\u0e08\u0e04\u0e23\u0e31\u0e1a \u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e21\u0e31\u0e19\u0e40\u0e02\u0e35\u0e22\u0e19\u0e41\u0e1a\u0e1a\u0e19\u0e31\u0e49\u0e19\u0e41\u0e15\u0e48\u0e1c\u0e21\u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e40\u0e2b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e40\u0e25\u0e02\u0e02\u0e36\u0e49\u0e19\u0e0b\u0e31\u0e01\u0e17\u0e35)<br \/>\n<span style=\"color: pink;\">\u0e2a\u0e35\u0e0a\u0e21\u0e1e\u0e39<\/span>: process \u0e1c\u0e35\u0e14\u0e34\u0e1a <img decoding=\"async\" class=\"smiley\" title=\"lol\" src=\"http:\/\/www.thaihosttalk.com\/Smileys\/default\/biggrin.gif\" border=\"0\" alt=\"lol\" \/> \u0e21\u0e31\u0e19\u0e04\u0e37\u0e2d process \u0e17\u0e35\u0e48\u0e15\u0e32\u0e22\/\u0e08\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27 \u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 clear \u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e08\u0e33\u0e44\u0e14\u0e49 \u0e2a\u0e48\u0e27\u0e19\u0e21\u0e32\u0e01\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e27\u0e01 process \u0e17\u0e35\u0e48\u0e23\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e08\u0e32\u0e01 hardware \u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2d\u0e22\u0e39\u0e48\u0e04\u0e23\u0e31\u0e1a (\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e41\u0e23\u0e21\u0e14\u0e49\u0e27\u0e22)<\/p>\n<p>\u0e1a\u0e23\u0e23\u0e17\u0e31\u0e14\u0e17\u0e35\u0e48 3: \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 CPU  \u0e2d\u0e31\u0e19\u0e19\u0e35\u0e49\u0e21\u0e35\u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e19\u0e34\u0e14\u0e2b\u0e19\u0e48\u0e2d\u0e22\u0e04\u0e23\u0e31\u0e1a \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e35\u0e48 cpu \u0e2b\u0e25\u0e32\u0e22 core \u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e25\u0e32\u0e22 cpu<br \/>\nCpu(s):\u00a0  4.0%us,\u00a0 0.7%sy,\u00a0 0.0%ni, 94.1%id,\u00a0 0.9%wa,\u00a0 0.0%hi,\u00a0 0.3%si,\u00a0 0.0%st<\/p>\n<p>\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15 \u0e14\u0e35\u0e46 \u0e21\u0e31\u0e19\u0e08\u0e30\u0e40\u0e02\u0e35\u0e22\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e1a\u0e23\u0e23\u0e17\u0e31\u0e14\u0e27\u0e48\u0e32 Cpu(s) &lt;&#8211; \u0e15\u0e23\u0e07 (s) \u0e2b\u0e21\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e20\u0e32\u0e1e\u0e23\u0e27\u0e21  cpu \u0e17\u0e38\u0e01 core<br \/>\n\u0e43\u0e2b\u0e49\u0e01\u0e14\u0e41\u0e1b\u0e49\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e25\u0e02 1 \u0e15\u0e23\u0e07\u0e41\u0e1b\u0e49\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e18\u0e23\u0e23\u0e21\u0e14\u0e32 \u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e02\u0e49\u0e32\u0e07\u0e46  \u0e1b\u0e38\u0e48\u0e21\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19 (` \/ ~) \u0e41\u0e25\u0e49\u0e27\u0e21\u0e31\u0e19\u0e08\u0e30\u0e41\u0e15\u0e01\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49\u0e04\u0e23\u0e31\u0e1a<\/p>\n<p>Cpu0\u00a0 :  27.6%us,\u00a0 7.2%sy,\u00a0 0.2%ni, 53.6%id, 10.9%wa,\u00a0 0.0%hi,\u00a0 0.5%si,\u00a0 0.0%st<br \/>\nCpu1\u00a0  : 28.1%us,\u00a0 7.2%sy,\u00a0 0.1%ni, 55.3%id,\u00a0 9.0%wa,\u00a0 0.0%hi,\u00a0 0.4%si,\u00a0  0.0%st<br \/>\nCpu2\u00a0 : 27.8%us,\u00a0 7.0%sy,\u00a0 0.2%ni, 62.0%id,\u00a0 2.8%wa,\u00a0 0.0%hi,\u00a0  0.2%si,\u00a0 0.0%st<br \/>\nCpu3\u00a0 : 28.1%us,\u00a0 7.3%sy,\u00a0 0.2%ni, 58.8%id,\u00a0  3.4%wa,\u00a0 0.2%hi,\u00a0 2.1%si,\u00a0 0.0%st<\/p>\n<p>\u0e41\u0e22\u0e01\u0e01\u0e31\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e2b\u0e21\u0e14\u0e40\u0e25\u0e22 \u0e27\u0e48\u0e32 CPU  \u0e44\u0e2b\u0e19\u0e01\u0e33\u0e25\u0e31\u0e07\u0e17\u0e33\u0e2d\u0e30\u0e44\u0e23\u0e2d\u0e22\u0e39\u0e48<br \/>\n\u0e17\u0e35\u0e19\u0e35\u0e49 \u0e41\u0e15\u0e48\u0e25\u0e30 column \u0e17\u0e35\u0e48\u0e21\u0e35\u0e15\u0e31\u0e27\u0e2d\u0e31\u0e01\u0e29\u0e23\u0e22\u0e48\u0e2d\u0e2a\u0e2d\u0e07\u0e15\u0e31\u0e27  \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e21\u0e32\u0e22\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e15\u0e32\u0e21\u0e19\u0e35\u0e49\u0e04\u0e23\u0e31\u0e1a<\/p>\n<p>us =&gt; user :: \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e01\u0e43\u0e0a\u0e49 CPU  \u0e15\u0e32\u0e21\u0e1b\u0e01\u0e15\u0e34\u0e02\u0e2d\u0e07\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e20\u0e32\u0e22\u0e43\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e19\u0e31\u0e49\u0e19\u0e46<br \/>\nsy =&gt; system  :: \u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e01\u0e43\u0e0a\u0e49\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a kernel \u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e2d\u0e22\u0e39\u0e48\u0e20\u0e32\u0e22\u0e43\u0e19 kernel  \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e40\u0e23\u0e35\u0e22\u0e01\u0e43\u0e0a\u0e49 hardware<br \/>\nni =&gt; nice ::  \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e25\u0e33\u0e14\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25 (priority) \u0e44\u0e27\u0e49\u0e2a\u0e25\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07 process  \u0e17\u0e35\u0e48\u0e21\u0e35 priority \u0e15\u0e48\u0e32\u0e07\u0e46 \u0e01\u0e31\u0e19\u0e40\u0e27\u0e25\u0e32\u0e40\u0e23\u0e35\u0e22\u0e01\u0e43\u0e0a\u0e49 cpu \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e46 \u0e01\u0e31\u0e19<br \/>\nid =&gt; idle ::  cpu \u0e17\u0e35\u0e48\u0e27\u0e48\u0e32\u0e07\u0e07\u0e32\u0e19<br \/>\nwa =&gt; iowait :: \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23 &#8216;\u0e40\u0e2a\u0e35\u0e22 \u0e40\u0e27\u0e25\u0e32\u0e23\u0e2d&#8217; \u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e01\u0e43\u0e0a\u0e49 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e1a hardware \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 harddisk ram  \u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d \u0e01\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e25\u0e19 (\u0e41\u0e15\u0e48\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e01\u0e47 harddisk \u0e41\u0e2b\u0e25\u0e30)<br \/>\nhi =&gt; ?<br \/>\nsi =&gt;  ? (\u0e2a\u0e32\u0e21\u0e2d\u0e31\u0e19\u0e19\u0e35\u0e49\u0e02\u0e2d\u0e2d\u0e20\u0e31\u0e22\u0e14\u0e49\u0e27\u0e22\u0e04\u0e23\u0e31\u0e1a \u0e44\u0e21\u0e48\u0e17\u0e23\u0e32\u0e1a\u0e08\u0e23\u0e34\u0e07\u0e46  \u0e2a\u0e48\u0e27\u0e19\u0e21\u0e32\u0e01\u0e01\u0e47\u0e44\u0e21\u0e48\u0e04\u0e48\u0e2d\u0e22\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e40\u0e17\u0e48\u0e32\u0e44\u0e2b\u0e23\u0e48\u0e14\u0e49\u0e27\u0e22)<br \/>\nst =&gt; ?<\/p>\n<p>\u0e1a\u0e23\u0e23\u0e17\u0e31\u0e14\u0e17\u0e35\u0e48 4-5: \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e08\u0e33 \u0e02\u0e2d\u0e23\u0e27\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e31\u0e27\u0e02\u0e49\u0e2d\u0e40\u0e14\u0e35\u0e22\u0e27\u0e40\u0e25\u0e22\u0e19\u0e30\u0e04\u0e23\u0e31\u0e1a \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e21\u0e31\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19<br \/>\nMem:&nbsp; &nbsp;<span style=\"color: red;\">8310380k total<\/span>,&nbsp; <span style=\"color: pink;\">4970936k used<\/span>,&nbsp; <span style=\"color: green;\">3339444k free<\/span>,&nbsp; &nbsp;<span style=\"color: orange;\">217448k buffers<\/span><br \/>\nSwap:&nbsp; <span style=\"color: purple;\">6225904k total<\/span>,&nbsp; &nbsp; <span style=\"color: blue;\">52816k used<\/span>,&nbsp; <span style=\"color: brown;\">6173088k free<\/span>,&nbsp; 3001860k cached<br \/>\n<span style=\"color: red;\">\u0e2a\u0e35\u0e41\u0e14\u0e07<\/span>: RAM \u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e17\u0e35\u0e48\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e44\u0e27\u0e49 \u0e41\u0e25\u0e30 OS \u0e21\u0e2d\u0e07\u0e40\u0e2b\u0e47\u0e19 (\u0e2b\u0e21\u0e32\u0e22\u0e16\u0e36\u0e07\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e08\u0e33\u0e2b\u0e25\u0e31\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e04\u0e23\u0e31\u0e1a)<br \/>\n<span style=\"color: pink;\">\u0e2a\u0e35\u0e0a\u0e21\u0e1e\u0e39<\/span>: \u0e43\u0e0a\u0e49\u0e41\u0e23\u0e21\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27 &#8220;\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14&#8221; \u0e40\u0e17\u0e48\u0e32\u0e44\u0e2b\u0e23\u0e48<br \/>\n<span style=\"color: green;\">\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27<\/span>: \u0e41\u0e23\u0e21\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e27\u0e48\u0e32\u0e07\u0e08\u0e23\u0e34\u0e07\u0e46 (\u0e04\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e08\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e2d\u0e30\u0e44\u0e23\u0e40\u0e25\u0e22)<br \/>\n<span style=\"color: orange;\">\u0e2a\u0e35\u0e2a\u0e49\u0e21<\/span>: \u0e41\u0e23\u0e21\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e43\u0e0a\u0e49\u0e40\u0e1b\u0e47\u0e19 buffer \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e01\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e2d\u0e48\u0e32\u0e19\/\u0e40\u0e02\u0e35\u0e22\u0e19\u0e25\u0e07 harddisk \u0e2b\u0e23\u0e37\u0e2d CPU<br \/>\n<span style=\"color: purple;\">\u0e2a\u0e35\u0e21\u0e48\u0e27\u0e07<\/span>: swap space \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e41\u0e23\u0e21\u0e40\u0e2a\u0e21\u0e37\u0e2d\u0e19\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e32\u0e01 harddisk \u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e41\u0e17\u0e19\u0e41\u0e23\u0e21 &#8212; \u0e1a\u0e19 windows \u0e21\u0e31\u0e19\u0e08\u0e30\u0e21\u0e35\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32 pagefile<br \/>\n<span style=\"color: blue;\">\u0e2a\u0e35\u0e19\u0e49\u0e33\u0e40\u0e07\u0e34\u0e19<\/span>: \u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 swap space \u0e21\u0e32\u0e01\u0e19\u0e49\u0e2d\u0e22\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e17\u0e48\u0e32\u0e44\u0e2b\u0e23\u0e48 (\u0e16\u0e36\u0e07\u0e21\u0e31\u0e19\u0e08\u0e30\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e43\u0e0a\u0e49\u0e01\u0e47\u0e15\u0e32\u0e21) \u0e41\u0e15\u0e48\u0e16\u0e49\u0e32\u0e15\u0e31\u0e27\u0e40\u0e25\u0e02\u0e41\u0e01\u0e27\u0e48\u0e07\u0e44\u0e1b\u0e21\u0e32 (\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a iowait \u0e1e\u0e38\u0e48\u0e07) \u0e2b\u0e21\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e27\u0e48\u0e32\u0e21\u0e35\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e41\u0e23\u0e21\u0e44\u0e21\u0e48\u0e1e\u0e2d\u0e08\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e32\u0e40\u0e02\u0e35\u0e22\u0e19\u0e25\u0e07 swap space<br \/>\n<span style=\"color: brown;\">\u0e2a\u0e35\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25<\/span>: \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 swap space \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19<br \/>\n\u0e2a\u0e35\u0e14\u0e33: \u0e40\u0e1b\u0e47\u0e19 file system memory cache \u0e04\u0e23\u0e31\u0e1a \u0e04\u0e37\u0e2d linux \u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49 ram \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e44\u0e1f\u0e25\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e01\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e1a\u0e48\u0e2d\u0e22\u0e46 \u0e44\u0e27\u0e49\u0e43\u0e19 ram (\u0e40\u0e1c\u0e37\u0e48\u0e2d\u0e21\u0e35\u0e2d\u0e30\u0e44\u0e23\u0e01\u0e47\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e2d\u0e32\u0e08\u0e32\u0e01\u0e41\u0e23\u0e21\u0e44\u0e1b\u0e40\u0e25\u0e22 \u0e40\u0e23\u0e47\u0e27\u0e01\u0e27\u0e48\u0e32\u0e40\u0e22\u0e2d\u0e30)<\/p>\n<p>\u0e27\u0e34\u0e18\u0e35\u0e04\u0e34\u0e14\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e41\u0e23\u0e21\u0e27\u0e48\u0e32\u0e07 \u0e43\u0e2b\u0e49\u0e04\u0e34\u0e14\u0e08\u0e32\u0e01 free + cached \u0e44\u0e21\u0e48\u0e19\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 cache  \u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19<br \/>\n\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e21\u0e31\u0e19\u0e08\u0e30\u0e16\u0e39\u0e01\u0e25\u0e1a\u0e2d\u0e2d\u0e01\u0e44\u0e14\u0e49\u0e40\u0e2a\u0e21\u0e2d\u0e16\u0e49\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 \u0e43\u0e0a\u0e49\u0e41\u0e23\u0e21\u0e08\u0e32\u0e01 process \u0e40\u0e22\u0e2d\u0e30\u0e46<\/p>\n<p>\u0e2a\u0e48\u0e27\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07  \u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23 process \u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 (\u0e41\u0e2a\u0e14\u0e07\u0e40\u0e17\u0e48\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e2d\u0e40\u0e2b\u0e25\u0e37\u0e2d)<br \/>\n\u0e40\u0e23\u0e35\u0e22\u0e07\u0e25\u0e33\u0e14\u0e31\u0e1a \u0e15\u0e32\u0e21\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 CPU \u0e02\u0e2d\u0e07 process \u0e19\u0e31\u0e49\u0e19\u0e46 (\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e44\u0e14\u0e49\u0e04\u0e23\u0e31\u0e1a)<\/p>\n<p>\u0e21\u0e35\u0e2b\u0e31\u0e27 \u0e02\u0e49\u0e2d\u0e15\u0e32\u0e21\u0e19\u0e35\u0e49<br \/>\n<strong>PID : \u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02 process id<br \/>\nUSER : user \u0e17\u0e35\u0e48 process  \u0e17\u0e33\u0e07\u0e32\u0e19<br \/>\n<\/strong>PR : priority \u0e02\u0e2d\u0e07 process \u0e17\u0e35\u0e48 nice \u0e40\u0e17\u0e48\u0e32\u0e01\u0e31\u0e19<br \/>\nNI :  \u0e23\u0e2b\u0e31\u0e2a nice \u0e40\u0e23\u0e35\u0e22\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07 process (\u0e22\u0e34\u0e48\u0e07\u0e19\u0e49\u0e2d\u0e22\u0e22\u0e34\u0e48\u0e07\u0e2a\u0e33\u0e04\u0e31\u0e0d)<br \/>\nVIRT :  \u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 virtual image \u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 (\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 process  \u0e22\u0e31\u0e19\u0e40\u0e15\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e01 library)<br \/>\nRES \/ SHR : \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e41\u0e23\u0e21\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07 private  (\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e20\u0e32\u0e22\u0e43\u0e19 app) \/ shared (ram \u0e01\u0e25\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e23\u0e30\u0e1a\u0e1a)<br \/>\nS : \u0e2a\u0e16\u0e32\u0e19\u0e30\u0e02\u0e2d\u0e07 process<br \/>\n%CPU  : \u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 CPU (\u0e19\u0e31\u0e1a\u0e15\u0e48\u0e2d core \u0e19\u0e30\u0e04\u0e23\u0e31\u0e1a) \u0e2a\u0e21\u0e21\u0e15\u0e34 cpu 4 core + process  \u0e23\u0e31\u0e19 4 thread \u0e41\u0e15\u0e48\u0e25\u0e30 thread \u0e40\u0e23\u0e35\u0e22\u0e01\u0e43\u0e0a\u0e49 cpu \u0e40\u0e15\u0e47\u0e21\u0e17\u0e35\u0e48 \u0e21\u0e31\u0e19\u0e01\u0e47\u0e02\u0e36\u0e49\u0e19 400  \u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e44\u0e14\u0e49\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19<br \/>\n%MEM : \u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 ram \u0e40\u0e1b\u0e47\u0e19 %<br \/>\nTIME+ :  &#8220;\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32&#8221; \u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e01\u0e43\u0e0a\u0e49 CPU \u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e23\u0e31\u0e19 process (\u0e40\u0e1e\u0e23\u0e32\u0e30 process  \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e17\u0e33\u0e07\u0e32\u0e19\u0e15\u0e25\u0e2d\u0e14\u0e40\u0e27\u0e25\u0e32)<br \/>\nCOMMAND : \u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e23\u0e31\u0e19 process<\/p>\n<p>\u0e25\u0e39\u0e01 \u0e40\u0e25\u0e48\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e02\u0e2d\u0e07 top \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2b\u0e32\u0e2d\u0e48\u0e32\u0e19\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07 man top \u0e19\u0e30\u0e04\u0e23\u0e31\u0e1a<br \/>\n\u0e21\u0e35\u0e2d\u0e35\u0e01 \u0e40\u0e1e\u0e35\u0e22\u0e1a \u0e19\u0e35\u0e48\u0e41\u0e04\u0e48\u0e41\u0e0b\u0e21\u0e40\u0e1b\u0e34\u0e49\u0e25\u0e46<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e2d\u0e32\u0e21\u0e32\u0e25\u0e07 blog \u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e0b\u0e31\u0e01\u0e17\u0e35&#8230; &#8221; top &#8220; (capture \u0e0a\u0e49\u0e32\u0e44\u0e1b\u0e2a\u0e2d\u0e07\u0e27\u0e34 \u0e40\u0e2a\u0e35\u0e22\u0e14\u0e32\u0e22\u0e08\u0e31\u0e07) \u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e25\u0e07\u0e40\u0e1e\u0e34\u0e48\u0e21 \u0e15\u0e34\u0e14\u0e21\u0e32\u0e01\u0e31\u0e1a os \u0e2d\u0e22\u0e39\u0e48\u0e41\u0e25\u0e49\u0e27\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e25\u0e07\u0e41\u0e1a\u0e1a minimal \u0e02\u0e19\u0e32\u0e14\u0e44\u0e2b\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e16\u0e49\u0e32\u0e17\u0e33\u0e2b\u0e32\u0e22\u0e44\u0e1b \u0e21\u0e31\u0e19\u0e08\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19 package &#8220;procps&#8221; \u0e04\u0e23\u0e31\u0e1a \u0e21\u0e31\u0e19\u0e1a\u0e2d\u0e01\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07 \u0e44\u0e25\u0e48\u0e17\u0e35\u0e25\u0e30\u0e1a\u0e23\u0e23\u0e17\u0e31\u0e14 \u0e40\u0e25\u0e22\u0e19\u0e30\u0e04\u0e23\u0e31\u0e1a (\u0e04\u0e34\u0e14\u0e08\u0e32\u0e01\u0e04\u0e48\u0e32\u0e1b\u0e01\u0e15\u0e34\u0e02\u0e2d\u0e07 centos \u0e0b\u0e36\u0e48\u0e07 os \u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e01\u0e47\u0e04\u0e25\u0e49\u0e32\u0e22\u0e46 \u0e01\u0e31\u0e19 \u0e2d\u0e32\u0e08\u0e21\u0e35\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1a\u0e49\u0e32\u0e07\u0e41\u0e25\u0e49\u0e27\u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32) \u0e1a\u0e23\u0e23\u0e17\u0e31\u0e14\u0e1a\u0e19\u0e2a\u0e38\u0e14 top &#8211; 09:13:20 up 187 days,&nbsp; 8:40,&nbsp; 1 user,&nbsp; load average: 0.43, 0.66, 0.61 \u0e2a\u0e35\u0e41\u0e14\u0e07: \u0e40\u0e27\u0e25\u0e32\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e02\u0e2d\u0e07 server \u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27: uptime (\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 boot OS \u0e02\u0e36\u0e49\u0e19\u0e21\u0e32) [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[129,130,131],"class_list":["post-715","post","type-post","status-publish","format-standard","hentry","category-linux","tag-monitor","tag-tools","tag-top"],"_links":{"self":[{"href":"https:\/\/www.icez.net\/blog\/wp-json\/wp\/v2\/posts\/715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.icez.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.icez.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.icez.net\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.icez.net\/blog\/wp-json\/wp\/v2\/comments?post=715"}],"version-history":[{"count":3,"href":"https:\/\/www.icez.net\/blog\/wp-json\/wp\/v2\/posts\/715\/revisions"}],"predecessor-version":[{"id":718,"href":"https:\/\/www.icez.net\/blog\/wp-json\/wp\/v2\/posts\/715\/revisions\/718"}],"wp:attachment":[{"href":"https:\/\/www.icez.net\/blog\/wp-json\/wp\/v2\/media?parent=715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.icez.net\/blog\/wp-json\/wp\/v2\/categories?post=715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.icez.net\/blog\/wp-json\/wp\/v2\/tags?post=715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}